{"id":330,"count":1,"description":"","link":"https:\/\/musuqilla.info\/en\/press-en\/tujaal-ediciones-en\/","name":"Tujaal Ediciones","slug":"tujaal-ediciones-en","taxonomy":"press","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tujaal Ediciones Archives - Musuq Illa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/musuqilla.info\/en\/press-en\/tujaal-ediciones-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tujaal Ediciones Archives - Musuq Illa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/musuqilla.info\/en\/press-en\/tujaal-ediciones-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Musuq Illa\" \/>\n<meta property=\"og:image\" content=\"https:\/\/musuqilla.info\/wp-content\/uploads\/2021\/04\/musuqilla.info_Facebook_Sharing_Default_quz_PE.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2880\" \/>\n\t<meta property=\"og:image:height\" content=\"1800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@MusuqIlla\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/press-en\\\/tujaal-ediciones-en\\\/\",\"url\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/press-en\\\/tujaal-ediciones-en\\\/\",\"name\":\"Tujaal Ediciones Archives - Musuq Illa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/press-en\\\/tujaal-ediciones-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/press-en\\\/tujaal-ediciones-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tujaal Ediciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/\",\"name\":\"Musuq Illa\",\"description\":\"Harawikuna runasimipi\",\"publisher\":{\"@id\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/#organization\",\"name\":\"Musuq Illa\",\"url\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/musuqilla.info\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/musuq_illa_masthead_logo_txt_E_2x_smaller.png?fit=348%2C264&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/musuqilla.info\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/musuq_illa_masthead_logo_txt_E_2x_smaller.png?fit=348%2C264&ssl=1\",\"width\":348,\"height\":264,\"caption\":\"Musuq Illa\"},\"image\":{\"@id\":\"https:\\\/\\\/musuqilla.info\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/MusuqIlla\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tujaal Ediciones Archives - Musuq Illa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/musuqilla.info\/en\/press-en\/tujaal-ediciones-en\/","og_locale":"en_US","og_type":"article","og_title":"Tujaal Ediciones Archives - Musuq Illa","og_url":"https:\/\/musuqilla.info\/en\/press-en\/tujaal-ediciones-en\/","og_site_name":"Musuq Illa","og_image":[{"width":2880,"height":1800,"url":"https:\/\/musuqilla.info\/wp-content\/uploads\/2021\/04\/musuqilla.info_Facebook_Sharing_Default_quz_PE.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@MusuqIlla","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/musuqilla.info\/en\/press-en\/tujaal-ediciones-en\/","url":"https:\/\/musuqilla.info\/en\/press-en\/tujaal-ediciones-en\/","name":"Tujaal Ediciones Archives - Musuq Illa","isPartOf":{"@id":"https:\/\/musuqilla.info\/en\/#website"},"breadcrumb":{"@id":"https:\/\/musuqilla.info\/en\/press-en\/tujaal-ediciones-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/musuqilla.info\/en\/press-en\/tujaal-ediciones-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/musuqilla.info\/en\/"},{"@type":"ListItem","position":2,"name":"Tujaal Ediciones"}]},{"@type":"WebSite","@id":"https:\/\/musuqilla.info\/en\/#website","url":"https:\/\/musuqilla.info\/en\/","name":"Musuq Illa","description":"Harawikuna runasimipi","publisher":{"@id":"https:\/\/musuqilla.info\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/musuqilla.info\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/musuqilla.info\/en\/#organization","name":"Musuq Illa","url":"https:\/\/musuqilla.info\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/musuqilla.info\/en\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/musuqilla.info\/wp-content\/uploads\/2020\/11\/musuq_illa_masthead_logo_txt_E_2x_smaller.png?fit=348%2C264&ssl=1","contentUrl":"https:\/\/i0.wp.com\/musuqilla.info\/wp-content\/uploads\/2020\/11\/musuq_illa_masthead_logo_txt_E_2x_smaller.png?fit=348%2C264&ssl=1","width":348,"height":264,"caption":"Musuq Illa"},"image":{"@id":"https:\/\/musuqilla.info\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/MusuqIlla"]}]}},"_links":{"self":[{"href":"https:\/\/musuqilla.info\/en\/wp-json\/wp\/v2\/press\/330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/musuqilla.info\/en\/wp-json\/wp\/v2\/press"}],"about":[{"href":"https:\/\/musuqilla.info\/en\/wp-json\/wp\/v2\/taxonomies\/press"}],"wp:post_type":[{"href":"https:\/\/musuqilla.info\/en\/wp-json\/wp\/v2\/product?press=330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}